{"id":780,"date":"2022-06-30T13:35:00","date_gmt":"2022-06-30T12:35:00","guid":{"rendered":"https:\/\/www.afaraba.org\/blog\/?p=780"},"modified":"2022-09-07T13:38:09","modified_gmt":"2022-09-07T12:38:09","slug":"premio-bebai","status":"publish","type":"post","link":"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/","title":{"rendered":"PREMIO BEBAI"},"content":{"rendered":"\n<p>Gracias por el reconocimiento!!<\/p>\n\n\n\n<p>Tenemos un Gran Equipo lleno de ilusi\u00f3n y profesionalidad que continuar\u00e1 trabajando por y para ayudar a todas las personas afectadas por Alzh\u00e9imer u otras demencias de \u00c1lava, asi como a sus familiares y amig@s.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.afaraba.org\/blog\/wp-content\/uploads\/2022\/09\/MG_9559-1024x683.jpg\" alt=\"\" class=\"wp-image-781\" srcset=\"http:\/\/www.afaraba.org\/blog\/wp-content\/uploads\/2022\/09\/MG_9559-1024x683.jpg 1024w, http:\/\/www.afaraba.org\/blog\/wp-content\/uploads\/2022\/09\/MG_9559-300x200.jpg 300w, http:\/\/www.afaraba.org\/blog\/wp-content\/uploads\/2022\/09\/MG_9559-768x512.jpg 768w, http:\/\/www.afaraba.org\/blog\/wp-content\/uploads\/2022\/09\/MG_9559-1536x1024.jpg 1536w, http:\/\/www.afaraba.org\/blog\/wp-content\/uploads\/2022\/09\/MG_9559-2048x1365.jpg 2048w, http:\/\/www.afaraba.org\/blog\/wp-content\/uploads\/2022\/09\/MG_9559-1200x800.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<p>&#x2665;&#xfe0f;&#x2665;&#xfe0f;Mila Esker!!! &#x2665;&#xfe0f;&#x2665;&#xfe0f;<\/p>\n\n\n\n<p>\u2018Hagamos un viaje al interior de tu memoria\u2019 en la que nuestra entidad acondicion\u00f3 una unidad m\u00f3vil para la realizaci\u00f3n de test y labores de orientaci\u00f3n social a personas alavesas ante la aparici\u00f3n de cambios a nivel cognitivo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gracias por el reconocimiento!! Tenemos un Gran Equipo lleno de ilusi\u00f3n y profesionalidad que continuar\u00e1 trabajando por y para ayudar a todas las personas afectadas por Alzh\u00e9imer u otras demencias de \u00c1lava, asi como a sus familiares y amig@s. &#x2665;&#xfe0f;&#x2665;&#xfe0f;Mila Esker!!! &#x2665;&#xfe0f;&#x2665;&#xfe0f; \u2018Hagamos un viaje al interior de tu memoria\u2019 en la que nuestra entidad &hellip; <a href=\"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abPREMIO BEBAI\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false},"categories":[3],"tags":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PREMIO BEBAI - AFARABA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PREMIO BEBAI - AFARABA\" \/>\n<meta property=\"og:description\" content=\"Gracias por el reconocimiento!! Tenemos un Gran Equipo lleno de ilusi\u00f3n y profesionalidad que continuar\u00e1 trabajando por y para ayudar a todas las personas afectadas por Alzh\u00e9imer u otras demencias de \u00c1lava, asi como a sus familiares y amig@s. &#x2665;&#xfe0f;&#x2665;&#xfe0f;Mila Esker!!! &#x2665;&#xfe0f;&#x2665;&#xfe0f; \u2018Hagamos un viaje al interior de tu memoria\u2019 en la que nuestra entidad &hellip; Continuar leyendo &quot;PREMIO BEBAI&quot;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/\" \/>\n<meta property=\"og:site_name\" content=\"AFARABA\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-30T12:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-07T12:38:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.afaraba.org\/blog\/wp-content\/uploads\/2022\/09\/MG_9559-1024x683.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.afaraba.org\/blog\/#\/schema\/person\/4a0ab48b67420072f420109f30843c71\"},\"headline\":\"PREMIO BEBAI\",\"datePublished\":\"2022-06-30T12:35:00+00:00\",\"dateModified\":\"2022-09-07T12:38:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/\"},\"wordCount\":100,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.afaraba.org\/blog\/#organization\"},\"articleSection\":[\"PERSONAS CUIDADORAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/\",\"url\":\"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/\",\"name\":\"PREMIO BEBAI - AFARABA\",\"isPartOf\":{\"@id\":\"https:\/\/www.afaraba.org\/blog\/#website\"},\"datePublished\":\"2022-06-30T12:35:00+00:00\",\"dateModified\":\"2022-09-07T12:38:09+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.afaraba.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PREMIO BEBAI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.afaraba.org\/blog\/#website\",\"url\":\"https:\/\/www.afaraba.org\/blog\/\",\"name\":\"AFARABA\",\"description\":\"BLOG AFARABA\",\"publisher\":{\"@id\":\"https:\/\/www.afaraba.org\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.afaraba.org\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.afaraba.org\/blog\/#organization\",\"name\":\"AFARABA\",\"url\":\"https:\/\/www.afaraba.org\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.afaraba.org\/blog\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.afaraba.org\/blog\/wp-content\/uploads\/2020\/11\/cropped-AFA_HC-BLOG2.jpg\",\"contentUrl\":\"http:\/\/www.afaraba.org\/blog\/wp-content\/uploads\/2020\/11\/cropped-AFA_HC-BLOG2.jpg\",\"width\":240,\"height\":89,\"caption\":\"AFARABA\"},\"image\":{\"@id\":\"https:\/\/www.afaraba.org\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.afaraba.org\/blog\/#\/schema\/person\/4a0ab48b67420072f420109f30843c71\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.afaraba.org\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/c2318eff2fb6ce04ef6dca732184cc5b?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/c2318eff2fb6ce04ef6dca732184cc5b?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"http:\/\/www.afaraba.org\/blog\/index.php\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PREMIO BEBAI - AFARABA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/","og_locale":"es_ES","og_type":"article","og_title":"PREMIO BEBAI - AFARABA","og_description":"Gracias por el reconocimiento!! Tenemos un Gran Equipo lleno de ilusi\u00f3n y profesionalidad que continuar\u00e1 trabajando por y para ayudar a todas las personas afectadas por Alzh\u00e9imer u otras demencias de \u00c1lava, asi como a sus familiares y amig@s. &#x2665;&#xfe0f;&#x2665;&#xfe0f;Mila Esker!!! &#x2665;&#xfe0f;&#x2665;&#xfe0f; \u2018Hagamos un viaje al interior de tu memoria\u2019 en la que nuestra entidad &hellip; Continuar leyendo \"PREMIO BEBAI\"","og_url":"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/","og_site_name":"AFARABA","article_published_time":"2022-06-30T12:35:00+00:00","article_modified_time":"2022-09-07T12:38:09+00:00","og_image":[{"url":"https:\/\/www.afaraba.org\/blog\/wp-content\/uploads\/2022\/09\/MG_9559-1024x683.jpg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/#article","isPartOf":{"@id":"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/"},"author":{"name":"admin","@id":"https:\/\/www.afaraba.org\/blog\/#\/schema\/person\/4a0ab48b67420072f420109f30843c71"},"headline":"PREMIO BEBAI","datePublished":"2022-06-30T12:35:00+00:00","dateModified":"2022-09-07T12:38:09+00:00","mainEntityOfPage":{"@id":"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/"},"wordCount":100,"commentCount":0,"publisher":{"@id":"https:\/\/www.afaraba.org\/blog\/#organization"},"articleSection":["PERSONAS CUIDADORAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/","url":"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/","name":"PREMIO BEBAI - AFARABA","isPartOf":{"@id":"https:\/\/www.afaraba.org\/blog\/#website"},"datePublished":"2022-06-30T12:35:00+00:00","dateModified":"2022-09-07T12:38:09+00:00","breadcrumb":{"@id":"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.afaraba.org\/blog\/index.php\/2022\/06\/30\/premio-bebai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.afaraba.org\/blog\/"},{"@type":"ListItem","position":2,"name":"PREMIO BEBAI"}]},{"@type":"WebSite","@id":"https:\/\/www.afaraba.org\/blog\/#website","url":"https:\/\/www.afaraba.org\/blog\/","name":"AFARABA","description":"BLOG AFARABA","publisher":{"@id":"https:\/\/www.afaraba.org\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.afaraba.org\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.afaraba.org\/blog\/#organization","name":"AFARABA","url":"https:\/\/www.afaraba.org\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.afaraba.org\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.afaraba.org\/blog\/wp-content\/uploads\/2020\/11\/cropped-AFA_HC-BLOG2.jpg","contentUrl":"http:\/\/www.afaraba.org\/blog\/wp-content\/uploads\/2020\/11\/cropped-AFA_HC-BLOG2.jpg","width":240,"height":89,"caption":"AFARABA"},"image":{"@id":"https:\/\/www.afaraba.org\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.afaraba.org\/blog\/#\/schema\/person\/4a0ab48b67420072f420109f30843c71","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.afaraba.org\/blog\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/c2318eff2fb6ce04ef6dca732184cc5b?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/c2318eff2fb6ce04ef6dca732184cc5b?s=96&d=mm&r=g","caption":"admin"},"url":"http:\/\/www.afaraba.org\/blog\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"http:\/\/www.afaraba.org\/blog\/index.php\/wp-json\/wp\/v2\/posts\/780"}],"collection":[{"href":"http:\/\/www.afaraba.org\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.afaraba.org\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.afaraba.org\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.afaraba.org\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=780"}],"version-history":[{"count":1,"href":"http:\/\/www.afaraba.org\/blog\/index.php\/wp-json\/wp\/v2\/posts\/780\/revisions"}],"predecessor-version":[{"id":782,"href":"http:\/\/www.afaraba.org\/blog\/index.php\/wp-json\/wp\/v2\/posts\/780\/revisions\/782"}],"wp:attachment":[{"href":"http:\/\/www.afaraba.org\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.afaraba.org\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=780"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.afaraba.org\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}